{"id":7268,"date":"2026-02-24T04:08:30","date_gmt":"2026-02-24T04:08:30","guid":{"rendered":"https:\/\/zenithyachtcharters.com\/my\/my-account\/"},"modified":"2026-03-25T14:14:44","modified_gmt":"2026-03-25T06:14:44","slug":"my-account","status":"publish","type":"page","link":"https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/","title":{"rendered":"My account"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7268\" class=\"elementor elementor-7268\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-719c63c e-flex e-con-boxed e-con e-parent\" data-id=\"719c63c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7b8d358 e-con-full e-flex e-con e-child\" data-id=\"7b8d358\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee7335b elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ee7335b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/th\/en\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">&gt;&gt;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/th\/en\/news\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">My account<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05b73b7 e-flex e-con-boxed e-con e-parent\" data-id=\"05b73b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22eee18 elementor-widget__width-initial oom-account e-my-account-tabs-vertical elementor-widget elementor-widget-woocommerce-my-account\" data-id=\"22eee18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-my-account.default\">\n\t\t\t\t\t<div class=\"e-my-account-tab e-my-account-tab__ \">\t\t\t<div class=\"woocommerce\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home &gt;&gt; My Account Dashboard Orders Gift Cards Downloads Addresses Account Details Logout Hello adm_oom (not adm_oom? Log out) From your account dashboard you can view your recent orders, manage your shipping and billing addresses, and edit your password and account details.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7268","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>My account - Zenith Yacht Charters - Thailand<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"My account - Zenith Yacht Charters - Thailand\" \/>\n<meta property=\"og:description\" content=\"Home &gt;&gt; My Account Dashboard Orders Gift Cards Downloads Addresses Account Details Logout Hello adm_oom (not adm_oom? Log out) From your account dashboard you can view your recent orders, manage your shipping and billing addresses, and edit your password and account details.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/\" \/>\n<meta property=\"og:site_name\" content=\"Zenith Yacht Charters - Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T06:14:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/my-account\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/my-account\\\/\",\"name\":\"My account - Zenith Yacht Charters - Thailand\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#website\"},\"datePublished\":\"2026-02-24T04:08:30+00:00\",\"dateModified\":\"2026-03-25T06:14:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/my-account\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/my-account\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/my-account\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"My account\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\",\"name\":\"Zenith Yacht Charters - Thailand\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#organization\",\"name\":\"Zenith Yacht Charters - Thailand\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"contentUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"width\":300,\"height\":199,\"caption\":\"Zenith Yacht Charters - Thailand\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"My account - Zenith Yacht Charters - Thailand","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"My account - Zenith Yacht Charters - Thailand","og_description":"Home &gt;&gt; My Account Dashboard Orders Gift Cards Downloads Addresses Account Details Logout Hello adm_oom (not adm_oom? Log out) From your account dashboard you can view your recent orders, manage your shipping and billing addresses, and edit your password and account details.","og_url":"https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/","og_site_name":"Zenith Yacht Charters - Thailand","article_modified_time":"2026-03-25T06:14:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/","url":"https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/","name":"My account - Zenith Yacht Charters - Thailand","isPartOf":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#website"},"datePublished":"2026-02-24T04:08:30+00:00","dateModified":"2026-03-25T06:14:44+00:00","breadcrumb":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/my-account\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zenithyachtcharters.com\/th\/en\/"},{"@type":"ListItem","position":2,"name":"My account"}]},{"@type":"WebSite","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#website","url":"https:\/\/zenithyachtcharters.com\/th\/en\/","name":"Zenith Yacht Charters - Thailand","description":"","publisher":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenithyachtcharters.com\/th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#organization","name":"Zenith Yacht Charters - Thailand","url":"https:\/\/zenithyachtcharters.com\/th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/02\/zyc_logo_v3-300x199-2.webp","contentUrl":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/02\/zyc_logo_v3-300x199-2.webp","width":300,"height":199,"caption":"Zenith Yacht Charters - Thailand"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/7268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/comments?post=7268"}],"version-history":[{"count":21,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/7268\/revisions"}],"predecessor-version":[{"id":8207,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/7268\/revisions\/8207"}],"wp:attachment":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/media?parent=7268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}