{"id":5706,"date":"2026-03-02T16:57:49","date_gmt":"2026-03-02T08:57:49","guid":{"rendered":"https:\/\/zenithyachtcharters.com\/sg\/?page_id=5706"},"modified":"2026-03-12T16:58:19","modified_gmt":"2026-03-12T08:58:19","slug":"sitemap","status":"publish","type":"page","link":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/","title":{"rendered":"Sitemap"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5706\" class=\"elementor elementor-5706\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6671355 e-flex e-con-boxed e-con e-parent\" data-id=\"6671355\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-de18eda e-con-full e-flex e-con e-child\" data-id=\"de18eda\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7312441 elementor-widget elementor-widget-image\" data-id=\"7312441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"251\" height=\"41\" src=\"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png\" class=\"attachment-full size-full wp-image-7366\" alt=\"inner_banner_archer-1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05fb58e elementor-widget__width-initial elementor-widget-laptop__width-inherit elementor-widget elementor-widget-heading\" data-id=\"05fb58e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sitemap<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-039e431 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"039e431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/th\/en\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">&gt;&gt;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sitemap<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-faaf9a3 e-flex e-con-boxed e-con e-parent\" data-id=\"faaf9a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9f04420 e-con-full e-flex e-con e-child\" data-id=\"9f04420\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be9eb81 elementor-widget elementor-widget-text-editor\" data-id=\"be9eb81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/browse-yachts\/\">Our Fleet<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/\">Experiences<\/a><ul><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/corporate-team-bonding-events\/\">Team Building<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/yacht-wedding-proposals-singapore\/\">Wedding and Proposals<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/fishing-and-adventure\/\">Fishing and Adventure<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/yacht-birthday-party-specials\/\">Birthdays and Specials<\/a><\/li><\/ul><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/yacht-dining\/\">Dine &amp; Play<\/a><ul><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/yacht-dining\/\">Yacht Dining<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/experiences\/water-toys\/\">Water Toys<\/a><\/li><\/ul><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/shop\/\">Shop<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/news\/\">News<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/yacht-brokerage-services\/\">Yacht Brokerage<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/contact\/\">Contact<\/a><\/li><li><a href=\"https:\/\/zenithyachtcharters.com\/th\/faq\/\">FAQs<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sitemap Home &gt;&gt; Sitemap Our Fleet Experiences Team Building Wedding and Proposals Fishing and Adventure Birthdays and Specials Dine &amp; Play Yacht Dining Water Toys Shop News Yacht Brokerage Contact FAQs<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5706","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sitemap - Zenith Yacht Charters - Thailand<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sitemap - Zenith Yacht Charters - Thailand\" \/>\n<meta property=\"og:description\" content=\"Sitemap Home &gt;&gt; Sitemap Our Fleet Experiences Team Building Wedding and Proposals Fishing and Adventure Birthdays and Specials Dine &amp; Play Yacht Dining Water Toys Shop News Yacht Brokerage Contact FAQs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/\" \/>\n<meta property=\"og:site_name\" content=\"Zenith Yacht Charters - Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T08:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/\",\"name\":\"Sitemap - Zenith Yacht Charters - Thailand\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecom02062026.zenithcharters.oomdcstaging.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/inner_banner_archer-1.png\",\"datePublished\":\"2026-03-02T08:57:49+00:00\",\"dateModified\":\"2026-03-12T08:58:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecom02062026.zenithcharters.oomdcstaging.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/inner_banner_archer-1.png\",\"contentUrl\":\"https:\\\/\\\/ecom02062026.zenithcharters.oomdcstaging.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/inner_banner_archer-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/sitemap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sitemap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\",\"name\":\"Zenith Yacht Charters - Thailand\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#organization\",\"name\":\"Zenith Yacht Charters - Thailand\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"contentUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"width\":300,\"height\":199,\"caption\":\"Zenith Yacht Charters - Thailand\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sitemap - Zenith Yacht Charters - Thailand","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Sitemap - Zenith Yacht Charters - Thailand","og_description":"Sitemap Home &gt;&gt; Sitemap Our Fleet Experiences Team Building Wedding and Proposals Fishing and Adventure Birthdays and Specials Dine &amp; Play Yacht Dining Water Toys Shop News Yacht Brokerage Contact FAQs","og_url":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/","og_site_name":"Zenith Yacht Charters - Thailand","article_modified_time":"2026-03-12T08:58:19+00:00","og_image":[{"url":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/","url":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/","name":"Sitemap - Zenith Yacht Charters - Thailand","isPartOf":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/#primaryimage"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/#primaryimage"},"thumbnailUrl":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png","datePublished":"2026-03-02T08:57:49+00:00","dateModified":"2026-03-12T08:58:19+00:00","breadcrumb":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/#primaryimage","url":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png","contentUrl":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/sitemap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zenithyachtcharters.com\/th\/en\/"},{"@type":"ListItem","position":2,"name":"Sitemap"}]},{"@type":"WebSite","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#website","url":"https:\/\/zenithyachtcharters.com\/th\/en\/","name":"Zenith Yacht Charters - Thailand","description":"","publisher":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenithyachtcharters.com\/th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#organization","name":"Zenith Yacht Charters - Thailand","url":"https:\/\/zenithyachtcharters.com\/th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/02\/zyc_logo_v3-300x199-2.webp","contentUrl":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/02\/zyc_logo_v3-300x199-2.webp","width":300,"height":199,"caption":"Zenith Yacht Charters - Thailand"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/5706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/comments?post=5706"}],"version-history":[{"count":3,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/5706\/revisions"}],"predecessor-version":[{"id":8095,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/5706\/revisions\/8095"}],"wp:attachment":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/media?parent=5706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}