{"id":1305,"date":"2026-02-12T08:49:45","date_gmt":"2026-02-12T00:49:45","guid":{"rendered":"https:\/\/zenithyachtcharters.com\/?page_id=1305"},"modified":"2026-04-23T18:08:28","modified_gmt":"2026-04-23T10:08:28","slug":"contact","status":"publish","type":"page","link":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1305\" class=\"elementor elementor-1305\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9443047 e-flex e-con-boxed e-con e-parent\" data-id=\"9443047\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83adfea e-con-full e-flex e-con e-child\" data-id=\"83adfea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-472776a elementor-widget elementor-widget-image\" data-id=\"472776a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"251\" height=\"41\" src=\"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png\" class=\"attachment-full size-full wp-image-7366\" alt=\"inner_banner_archer-1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5ba810 elementor-widget__width-initial elementor-widget-laptop__width-inherit elementor-widget elementor-widget-heading\" data-id=\"c5ba810\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Contact<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bbadf9 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4bbadf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/th\/en\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">&gt;&gt;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contact<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4cb37a e-flex e-con-boxed e-con e-parent\" data-id=\"b4cb37a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3f3c24e e-con-full e-flex e-con e-child\" data-id=\"3f3c24e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-99f1d1b e-con-full e-flex e-con e-child\" data-id=\"99f1d1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-00ca56f e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"00ca56f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1bdfc17 e-con-full e-flex e-con e-child\" data-id=\"1bdfc17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db70d2c elementor-widget elementor-widget-spacer\" data-id=\"db70d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-227c9ba e-con-full e-flex e-con e-child\" data-id=\"227c9ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bc1c11 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"9bc1c11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/zenithyachtcharters.com\/my\/wp-content\/uploads\/sites\/3\/2026\/03\/contact-pic-1.webp\" title=\"\" alt=\"contact-pic (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9c6338 e-con-full e-flex e-con e-child\" data-id=\"c9c6338\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f0bfe66 e-con-full e-flex e-con e-child\" data-id=\"f0bfe66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-cd6e334 e-con-full e-flex e-con e-child\" data-id=\"cd6e334\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e205d15 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"e205d15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zenith Yacht Charters <span style=\"color:black\">Pte Ltd <\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8418507 elementor-view-stacked elementor-position-inline-start elementor-tablet-position-inline-start elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit imagebox-contact elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"8418507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCall Us Now\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSales &amp; charter enquiries :<br>\n<a href=\"tel:+6580225028\" style=\"color:#ffffff;text-decoration:none\">+65 8022 5028<\/a>\n<br><br>\n\nMarketing and collaborations :<br>\n<a href=\"tel:+6589806526\" style=\"color:#ffffff;text-decoration:none\">+65 8980 6526<\/a>\n<br><br>\n\nBrokerage &amp; yacht management :<br>\n<a href=\"tel:+6581120209\" style=\"color:#ffffff;text-decoration:none\">+65 8112 0209<\/a>\n<br><br>\n\nHuman Resource:<br>\n<a href=\"tel:+6594601456\" style=\"color:#ffffff;text-decoration:none\">+65 9460 1456<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-687096b elementor-view-stacked elementor-position-inline-start elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit imagebox-contact elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"687096b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOur Location\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/KvEj7DzTChV8kRx7A\" target=\"_blank\" style=\"color:#ffffff;text-decoration:none\">\n   1 Harbourfront Ave, #13-03, Keppel Bay <\/br>Tower, Singapore 098632\n<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-116cb13 elementor-view-stacked elementor-position-inline-start elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit imagebox-contact elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"116cb13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEmail Us\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"mailto:info@zenithyachtcharters.com\" style=\"color:#ffffff;text-decoration:none\">\n   info@zenithyachtcharters.com\n<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-387ba42 e-con-full e-flex e-con e-child\" data-id=\"387ba42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ca5a126 e-con-full e-flex e-con e-child\" data-id=\"ca5a126\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95a566c elementor-widget elementor-widget-image\" data-id=\"95a566c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"299\" height=\"40\" src=\"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/archer-1-1.webp\" class=\"attachment-full size-full wp-image-7365\" alt=\"archer-1-1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96b6282 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"96b6282\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">SEND US AN ENQUIRY<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73ca2aa elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"73ca2aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Experience the Unique<\/br>\nAdventure With Us.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61f53ee elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"61f53ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>If you have any enquiry, please do not hesitate to contact us. Leave us a message and we will get back to you shortly.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-494c731 elementor-button-align-center contact-form-class elementor-widget elementor-widget-oom-elementor-form\" data-id=\"494c731\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;100&quot;}\" data-widget_type=\"oom-elementor-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"oom-form-widget\"><form id=\"oom-form-494c731\" class=\"oom-custom-form elementor-form\" method=\"post\" enctype=\"multipart\/form-data\"><div class=\"elementor-form-fields-wrapper\"><input type=\"hidden\" name=\"form_id\" value=\"494c731\"\/><input type=\"hidden\" name=\"post_id\" value=\"1305\"><input type=\"hidden\" name=\"page_id\" value=\"1305\"\/><input type=\"hidden\" name=\"form_name\" value=\"Contact Form\"\/><div class=\"form-field elementor-field-group elementor-column elementor-field-type-text elementor-col-50\"><label class=\"elementor-field-label\" for=\"field_c_name\">Your Name<\/label><input type=\"text\" id=\"field_c_name\" name=\"field_c_name\" placeholder=\"\" class=\"elementor-field elementor-field-textual elementor-size-sm\" required><\/div><div class=\"form-field elementor-field-group elementor-column elementor-field-type-text elementor-col-50\"><label class=\"elementor-field-label\" for=\"field_c_company_name\">Your Company Name<\/label><input type=\"text\" id=\"field_c_company_name\" name=\"field_c_company_name\" placeholder=\"\" class=\"elementor-field elementor-field-textual elementor-size-sm\" required><\/div><div class=\"form-field elementor-field-group elementor-column elementor-field-type-email elementor-col-50\"><label class=\"elementor-field-label\" for=\"field_c_email\">Your Email Address<\/label><input type=\"email\" id=\"field_c_email\" name=\"field_c_email\" placeholder=\"\" class=\"elementor-field elementor-field-textual elementor-size-sm\" required><\/div><div class=\"form-field elementor-field-group elementor-column elementor-field-type-tel elementor-col-50\"><label class=\"elementor-field-label\" for=\"field_c_phone\">Your Phone Number<\/label><input type=\"tel\" id=\"field_c_phone\" name=\"field_c_phone\" placeholder=\"\" class=\"oom-phone elementor-field elementor-field-textual elementor-size-sm\" required><\/div><div class=\"form-field elementor-field-group elementor-column elementor-field-type-text elementor-col-100\"><label class=\"elementor-field-label\" for=\"field_c_message\">Your Message<\/label><input type=\"text\" id=\"field_c_message\" name=\"field_c_message\" placeholder=\"\" class=\"elementor-field elementor-field-textual elementor-size-sm\" ><\/div>\n\t\t\t\t\t\t<div style=\"display:none;\">\n\t\t\t\t\t\t\t<input type=\"text\" id=\"oom_form\" name=\"oom_form\">\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t\t\t<button class=\"elementor-button oom_form_submit_button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Let's Talk<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"loading-spinner\"><\/div>\n\t\t\t\t\t\t<div class=\"form-message\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/form>\n\n\t\t\t\t\t<script>\n\t\t\t\t\t\tjQuery(document).ready(function ($) {\n\t\t\t\t\t\t\tconst formId = '494c731';\n\t\t\t\t\t\t\tconst formSelector = `#oom-form-${formId}`;\n\t\t\t\t\t\t\tconst phoneInputSelector = `${formSelector} input[type='tel']`;\n\t\t\t\t\t\t\tconst messageSelector = `${formSelector} .form-message`;\n\t\t\t\t\t\t\tconst spinnerSelector = `${formSelector} .loading-spinner`;\n\t\t\t\t\t\t\tconst phoneInput = document.querySelector(phoneInputSelector);\n\n\t\t\t\t\t\t\tlet iti = null;\n\n\t\t\t\t\t\t\t\/\/ Initialize intl-tel-input for this specific form\n\t\t\t\t\t\t\tif (phoneInput) {\n\t\t\t\t\t\t\t\titi = window.intlTelInput(phoneInput, {\n\t\t\t\t\t\t\t\t\tnationalMode: true,\n\t\t\t\t\t\t\t\t\tinitialCountry: \"auto\",\n\t\t\t\t\t\t\t\t\tgeoIpLookup: function (callback) {\n\t\t\t\t\t\t\t\t\t\tfetch(\"https:\/\/ipapi.co\/json\")\n\t\t\t\t\t\t\t\t\t\t\t.then((res) => res.json())\n\t\t\t\t\t\t\t\t\t\t\t.then((data) => callback(data.country_code))\n\t\t\t\t\t\t\t\t\t\t\t.catch(() => callback(\"SG\")); \/\/ Default fallback to Singapore\n\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\tutilsScript: \"..\/js\/utils.js\", \/\/ Or CDN version\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t\t\/\/ Always overwrite the input value with the full international number\n\t\t\t\t\t\t\t\tfunction updatePhoneNumber() {\n\t\t\t\t\t\t\t\t\tphoneInput.value = iti.getNumber();\n\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\tphoneInput.addEventListener('countrychange', updatePhoneNumber);\n\t\t\t\t\t\t\t\tphoneInput.addEventListener('blur', updatePhoneNumber);\n\t\t\t\t\t\t\t\tphoneInput.addEventListener('input', updatePhoneNumber);\n\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\/\/ Form submission handling\n\t\t\t\t\t\t\t$(formSelector).on('submit', function (e) {\n\t\t\t\t\t\t\t\te.preventDefault();\n\n\t\t\t\t\t\t\t\tif (iti && !iti.isValidNumber()) {\n\t\t\t\t\t\t\t\t\t$(messageSelector).html('<p>Invalid phone number. Please enter a valid phone number.<\/p>');\n\t\t\t\t\t\t\t\t\tphoneInput.focus();\n\t\t\t\t\t\t\t\t\treturn;\n\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\t$(spinnerSelector).show();\n\n\t\t\t\t\t\t\t\tconst serialized = $(this).serialize();\n\t\t\t\t\t\t\t\tconst fd = new FormData(this);\n\t\t\t\t\t\t\t\tfd.append('action', 'dynamic_form_submit');\n\t\t\t\t\t\t\t\tfd.append('nonce', '8a3387a86b');\n\t\t\t\t\t\t\t\tfd.append('form_data', serialized);\n\n\t\t\t\t\t\t\t\t$.ajax({\n\t\t\t\t\t\t\t\t\turl: 'https:\/\/zenithyachtcharters.com\/th\/wp-admin\/admin-ajax.php',\n\t\t\t\t\t\t\t\t\ttype: 'POST',\n\t\t\t\t\t\t\t\t\tdata: fd,\n\t\t\t\t\t\t\t\t\tprocessData: false,\n\t\t\t\t\t\t\t\t\tcontentType: false,\n\t\t\t\t\t\t\t\t\tsuccess: function (response) {\n\t\t\t\t\t\t\t\t\t\tconsole.log(response);\n\t\t\t\t\t\t\t\t\t\t$(messageSelector).html(`<p>${response.data.message}<\/p>`);\n\n\t\t\t\t\t\t\t\t\t\tif(response.success) {\n\t\t\t\t\t\t\t\t\t\t\t$(formSelector)[0].reset();\n\t\t\t\t\t\t\t\t\t\t\tif (response.data.redirect_url) {\n\t\t\t\t\t\t\t\t\t\t\t\twindow.location.href = response.data.redirect_url;\n\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\terror: function (response) {\n\t\t\t\t\t\t\t\t\t\tconsole.error(response);\n\t\t\t\t\t\t\t\t\t\t$(messageSelector).html('<p>An error occurred. Please try again.<\/p>');\n\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\tcomplete: function () {\n\t\t\t\t\t\t\t\t\t\t$(spinnerSelector).hide();\n\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t});\n\t\t\t\t\t<\/script>\n\n\n\n\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact Home &gt;&gt; Contact Zenith Yacht Charters Pte Ltd Call Us Now Sales &amp; charter enquiries : +65 8022 5028 Marketing and collaborations : +65 8980 6526 Brokerage &amp; yacht management : +65 8112 0209 Human Resource: +65 9460 1456 Our Location 1 Harbourfront Ave, #13-03, Keppel Bay Tower, Singapore 098632 Email Us info@zenithyachtcharters.com SEND [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1305","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Us - Zenith Yacht Charter<\/title>\n<meta name=\"description\" content=\"Contact us today to embark on your unforgettable luxury yacht experience. Whether you&#039;re planning a glamorous party, a relaxing vacation, or a corporate event, we are here to assist you.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us - Zenith Yacht Charter\" \/>\n<meta property=\"og:description\" content=\"Contact us today to embark on your unforgettable luxury yacht experience. Whether you&#039;re planning a glamorous party, a relaxing vacation, or a corporate event, we are here to assist you.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Zenith Yacht Charters - Thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T10:08:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"251\" \/>\n\t<meta property=\"og:image:height\" content=\"41\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/\",\"name\":\"Contact Us - Zenith Yacht Charter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/inner_banner_archer-1.png\",\"datePublished\":\"2026-02-12T00:49:45+00:00\",\"dateModified\":\"2026-04-23T10:08:28+00:00\",\"description\":\"Contact us today to embark on your unforgettable luxury yacht experience. Whether you're planning a glamorous party, a relaxing vacation, or a corporate event, we are here to assist you.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/inner_banner_archer-1.png\",\"contentUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/03\\\/inner_banner_archer-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\",\"name\":\"Zenith Yacht Charters - Thailand\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#organization\",\"name\":\"Zenith Yacht Charters - Thailand\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"contentUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"width\":300,\"height\":199,\"caption\":\"Zenith Yacht Charters - Thailand\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us - Zenith Yacht Charter","description":"Contact us today to embark on your unforgettable luxury yacht experience. Whether you're planning a glamorous party, a relaxing vacation, or a corporate event, we are here to assist you.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Contact Us - Zenith Yacht Charter","og_description":"Contact us today to embark on your unforgettable luxury yacht experience. Whether you're planning a glamorous party, a relaxing vacation, or a corporate event, we are here to assist you.","og_url":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/","og_site_name":"Zenith Yacht Charters - Thailand","article_modified_time":"2026-04-23T10:08:28+00:00","og_image":[{"width":251,"height":41,"url":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/","url":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/","name":"Contact Us - Zenith Yacht Charter","isPartOf":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/#primaryimage"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/#primaryimage"},"thumbnailUrl":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png","datePublished":"2026-02-12T00:49:45+00:00","dateModified":"2026-04-23T10:08:28+00:00","description":"Contact us today to embark on your unforgettable luxury yacht experience. Whether you're planning a glamorous party, a relaxing vacation, or a corporate event, we are here to assist you.","breadcrumb":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenithyachtcharters.com\/th\/en\/contact\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/#primaryimage","url":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png","contentUrl":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/03\/inner_banner_archer-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zenithyachtcharters.com\/th\/en\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#website","url":"https:\/\/zenithyachtcharters.com\/th\/en\/","name":"Zenith Yacht Charters - Thailand","description":"","publisher":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenithyachtcharters.com\/th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#organization","name":"Zenith Yacht Charters - Thailand","url":"https:\/\/zenithyachtcharters.com\/th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/02\/zyc_logo_v3-300x199-2.webp","contentUrl":"https:\/\/zenithyachtcharters.com\/th\/wp-content\/uploads\/sites\/4\/2026\/02\/zyc_logo_v3-300x199-2.webp","width":300,"height":199,"caption":"Zenith Yacht Charters - Thailand"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/1305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/comments?post=1305"}],"version-history":[{"count":13,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/1305\/revisions"}],"predecessor-version":[{"id":10113,"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/pages\/1305\/revisions\/10113"}],"wp:attachment":[{"href":"https:\/\/zenithyachtcharters.com\/th\/en\/wp-json\/wp\/v2\/media?parent=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}