{"id":1740,"date":"2026-02-13T10:58:48","date_gmt":"2026-02-13T02:58:48","guid":{"rendered":"https:\/\/zenithyachtcharters.com\/?post_type=yachts&#038;p=1740"},"modified":"2026-04-30T13:24:27","modified_gmt":"2026-04-30T05:24:27","slug":"providence","status":"publish","type":"yachts","link":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/","title":{"rendered":"Providence"},"content":{"rendered":"<p>Experience the pinnacle of timeless elegance\u00a0on the water with luxurious amenities including\u00a0a spacious saloon, inviting aft cockpit,\u00a0convenient swim platform, and a generous\u00a0flybridge equipped for entertainment and\u00a0barbecues, with a licensed capacity of 50 pax.\u200b<\/p>\n<p>\u200bWith its fully teak deck, Providence is the ideal\u00a0setting for your intimate gatherings and events,\u00a0promising to create lasting memories for all\u00a0who come aboard.<\/p>\n","protected":false},"author":16,"featured_media":6707,"template":"","amenities":[406],"water-toys":[168,172,174,251],"destinations":[126],"yacht-types":[41],"charter-types":[537],"brands":[156],"class_list":["post-1740","yachts","type-yachts","status-publish","has-post-thumbnail","hentry","amenities-projector-system-chargeable","water-toys-floating-mat","water-toys-jetski-pre-order-chargeable","water-toys-kayak","water-toys-sea-scooter-pre-order-chargeable","destinations-singapore","yacht-types-motoryacht","charter-types-537","brands-dragos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Providence - Zenith Yacht Charters - Singapore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Providence - Zenith Yacht Charters - Singapore\" \/>\n<meta property=\"og:description\" content=\"Experience the pinnacle of timeless elegance\u00a0on the water with luxurious amenities including\u00a0a spacious saloon, inviting aft cockpit,\u00a0convenient swim platform, and a generous\u00a0flybridge equipped for entertainment and\u00a0barbecues, with a licensed capacity of 50 pax.\u200b \u200bWith its fully teak deck, Providence is the ideal\u00a0setting for your intimate gatherings and events,\u00a0promising to create lasting memories for all\u00a0who come aboard.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/\" \/>\n<meta property=\"og:site_name\" content=\"Zenith Yacht Charters - Singapore\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T05:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/Providence.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1214\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/\",\"name\":\"Providence - Zenith Yacht Charters - Singapore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Providence.webp\",\"datePublished\":\"2026-02-13T02:58:48+00:00\",\"dateModified\":\"2026-04-30T05:24:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Providence.webp\",\"contentUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Providence.webp\",\"width\":2048,\"height\":1214},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/providence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yachts\",\"item\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/yachts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Providence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/\",\"name\":\"Zenith Yacht Charters - Singapore\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#organization\",\"name\":\"Zenith Yacht Charters - Singapore\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"contentUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"width\":300,\"height\":199,\"caption\":\"Zenith Yacht Charters - Singapore\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Providence - Zenith Yacht Charters - Singapore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/","og_locale":"en_US","og_type":"article","og_title":"Providence - Zenith Yacht Charters - Singapore","og_description":"Experience the pinnacle of timeless elegance\u00a0on the water with luxurious amenities including\u00a0a spacious saloon, inviting aft cockpit,\u00a0convenient swim platform, and a generous\u00a0flybridge equipped for entertainment and\u00a0barbecues, with a licensed capacity of 50 pax.\u200b \u200bWith its fully teak deck, Providence is the ideal\u00a0setting for your intimate gatherings and events,\u00a0promising to create lasting memories for all\u00a0who come aboard.","og_url":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/","og_site_name":"Zenith Yacht Charters - Singapore","article_modified_time":"2026-04-30T05:24:27+00:00","og_image":[{"width":2048,"height":1214,"url":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/Providence.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/","url":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/","name":"Providence - Zenith Yacht Charters - Singapore","isPartOf":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/#primaryimage"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/#primaryimage"},"thumbnailUrl":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/Providence.webp","datePublished":"2026-02-13T02:58:48+00:00","dateModified":"2026-04-30T05:24:27+00:00","breadcrumb":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/#primaryimage","url":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/Providence.webp","contentUrl":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/Providence.webp","width":2048,"height":1214},{"@type":"BreadcrumbList","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/providence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zenithyachtcharters.com\/sg\/en\/"},{"@type":"ListItem","position":2,"name":"Yachts","item":"https:\/\/zenithyachtcharters.com\/sg\/en\/yachts\/"},{"@type":"ListItem","position":3,"name":"Providence"}]},{"@type":"WebSite","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#website","url":"https:\/\/zenithyachtcharters.com\/sg\/en\/","name":"Zenith Yacht Charters - Singapore","description":"","publisher":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenithyachtcharters.com\/sg\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#organization","name":"Zenith Yacht Charters - Singapore","url":"https:\/\/zenithyachtcharters.com\/sg\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/zyc_logo_v3-300x199-2.webp","contentUrl":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/zyc_logo_v3-300x199-2.webp","width":300,"height":199,"caption":"Zenith Yacht Charters - Singapore"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/yachts\/1740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/yachts"}],"about":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/types\/yachts"}],"author":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/users\/16"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/media\/6707"}],"wp:attachment":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/media?parent=1740"}],"wp:term":[{"taxonomy":"amenities","embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/amenities?post=1740"},{"taxonomy":"water-toys","embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/water-toys?post=1740"},{"taxonomy":"destinations","embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/destinations?post=1740"},{"taxonomy":"yacht-types","embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/yacht-types?post=1740"},{"taxonomy":"charter-types","embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/charter-types?post=1740"},{"taxonomy":"brands","embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/brands?post=1740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}