{"id":276,"date":"2026-02-06T15:23:50","date_gmt":"2026-02-06T07:23:50","guid":{"rendered":"https:\/\/zenithyachtcharters.com\/cart\/"},"modified":"2026-03-31T19:10:49","modified_gmt":"2026-03-31T11:10:49","slug":"cart","status":"publish","type":"page","link":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"276\" class=\"elementor elementor-276\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4402dd6 e-flex e-con-boxed e-con e-parent\" data-id=\"4402dd6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dec54e9 e-con-full e-flex e-con e-child\" data-id=\"dec54e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d89727 elementor-widget elementor-widget-image\" data-id=\"5d89727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"251\" height=\"41\" src=\"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/inner_banner_archer.png\" class=\"attachment-full size-full wp-image-3663\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10d1eee elementor-widget__width-initial elementor-widget-laptop__width-inherit elementor-widget elementor-widget-heading\" data-id=\"10d1eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cart<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98116a3 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"98116a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/sg\/en\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">&gt;&gt;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cart<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7e1926 e-flex e-con-boxed e-con e-parent\" data-id=\"e7e1926\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cart Home &gt;&gt; Cart<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-276","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cart - Zenith Yacht Charters - Singapore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cart - Zenith Yacht Charters - Singapore\" \/>\n<meta property=\"og:description\" content=\"Cart Home &gt;&gt; Cart\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/\" \/>\n<meta property=\"og:site_name\" content=\"Zenith Yacht Charters - Singapore\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T11:10:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/inner_banner_archer.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/\",\"name\":\"Cart - Zenith Yacht Charters - Singapore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecom02062026.zenithcharters.oomdcstaging.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/inner_banner_archer.png\",\"datePublished\":\"2026-02-06T07:23:50+00:00\",\"dateModified\":\"2026-03-31T11:10:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecom02062026.zenithcharters.oomdcstaging.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/inner_banner_archer.png\",\"contentUrl\":\"https:\\\/\\\/ecom02062026.zenithcharters.oomdcstaging.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/inner_banner_archer.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/cart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/\",\"name\":\"Zenith Yacht Charters - Singapore\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#organization\",\"name\":\"Zenith Yacht Charters - Singapore\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"contentUrl\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/zyc_logo_v3-300x199-2.webp\",\"width\":300,\"height\":199,\"caption\":\"Zenith Yacht Charters - Singapore\"},\"image\":{\"@id\":\"https:\\\/\\\/zenithyachtcharters.com\\\/sg\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cart - Zenith Yacht Charters - Singapore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/","og_locale":"en_US","og_type":"article","og_title":"Cart - Zenith Yacht Charters - Singapore","og_description":"Cart Home &gt;&gt; Cart","og_url":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/","og_site_name":"Zenith Yacht Charters - Singapore","article_modified_time":"2026-03-31T11:10:49+00:00","og_image":[{"url":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/inner_banner_archer.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/","url":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/","name":"Cart - Zenith Yacht Charters - Singapore","isPartOf":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/#primaryimage"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/#primaryimage"},"thumbnailUrl":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/inner_banner_archer.png","datePublished":"2026-02-06T07:23:50+00:00","dateModified":"2026-03-31T11:10:49+00:00","breadcrumb":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/#primaryimage","url":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/inner_banner_archer.png","contentUrl":"https:\/\/ecom02062026.zenithcharters.oomdcstaging.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/inner_banner_archer.png"},{"@type":"BreadcrumbList","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/cart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zenithyachtcharters.com\/sg\/en\/"},{"@type":"ListItem","position":2,"name":"Cart"}]},{"@type":"WebSite","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#website","url":"https:\/\/zenithyachtcharters.com\/sg\/en\/","name":"Zenith Yacht Charters - Singapore","description":"","publisher":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zenithyachtcharters.com\/sg\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#organization","name":"Zenith Yacht Charters - Singapore","url":"https:\/\/zenithyachtcharters.com\/sg\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/zyc_logo_v3-300x199-2.webp","contentUrl":"https:\/\/zenithyachtcharters.com\/sg\/wp-content\/uploads\/sites\/2\/2026\/02\/zyc_logo_v3-300x199-2.webp","width":300,"height":199,"caption":"Zenith Yacht Charters - Singapore"},"image":{"@id":"https:\/\/zenithyachtcharters.com\/sg\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/pages\/276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":7,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/pages\/276\/revisions"}],"predecessor-version":[{"id":5388,"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/pages\/276\/revisions\/5388"}],"wp:attachment":[{"href":"https:\/\/zenithyachtcharters.com\/sg\/en\/wp-json\/wp\/v2\/media?parent=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}